{"id":23605,"date":"2022-03-24T17:11:31","date_gmt":"2022-03-25T00:11:31","guid":{"rendered":"https:\/\/genuscap.com\/?p=23605"},"modified":"2026-03-17T13:38:23","modified_gmt":"2026-03-17T20:38:23","slug":"how-canadian-impact-investors-are-empowering-latin-american-women","status":"publish","type":"post","link":"https:\/\/genuscap.com\/fr\/how-canadian-impact-investors-are-empowering-latin-american-women\/","title":{"rendered":"Comment les investisseurs d'impact canadiens renforcent l'autonomie des femmes latino-am\u00e9ricaines"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"23605\" class=\"elementor elementor-23605\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a95435 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"5a95435\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a63bbf4\" data-id=\"a63bbf4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7182a83 elementor-widget elementor-widget-text-editor\" data-id=\"7182a83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Chaque investisseur souhaite que ses investissements soient performants sur le plan financier. Les investisseurs d'impact souhaitent \u00e9galement qu'ils soient performants sur le plan social, en proposant des solutions \u00e0 des probl\u00e8mes sociaux importants. <\/span><a href=\"https:\/\/deetkenimpact.com\/\"><span style=\"font-weight: 400;\">Impact Deetken<\/span><\/a><span style=\"font-weight: 400;\"> a trouv\u00e9 un moyen d'obtenir ces deux r\u00e9sultats pour les investisseurs canadiens qui cherchent \u00e0 faire progresser l'\u00e9galit\u00e9 des sexes par le biais d'investissements priv\u00e9s.\u00a0<\/span><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400;\">Son <\/span><a href=\"https:\/\/iluwomensempowermentfund.com\/\"><span style=\"font-weight: 400;\">Fonds d'autonomisation des femmes d'Ilu<\/span><\/a><span style=\"font-weight: 400;\">Lanc\u00e9 en 2019, Pro Mujer a permis aux investisseurs canadiens d'acc\u00e9der \u00e0 l'investissement priv\u00e9 bas\u00e9 sur le genre en Am\u00e9rique latine gr\u00e2ce \u00e0 sa coentreprise avec Pro Mujer. Et les r\u00e9sultats sont impressionnants, avec $45 millions de dollars canadiens engag\u00e9s par 70 investisseurs priv\u00e9s, dont 40 % sont des femmes.\u00a0<\/span><\/p><p><br \/><span style=\"font-weight: 400;\">Ilu\" signifie \"planter\" dans la langue du peuple aymara. <\/span><span style=\"font-weight: 400;\">les r\u00e9gions des Andes et de l'Altiplano en Am\u00e9rique du Sud, en Argentine, en Bolivie, au Chili et au P\u00e9rou. L'objectif d'Ilu est de semer les graines de la prosp\u00e9rit\u00e9 \u00e9conomique pour les femmes de ces r\u00e9gions.<\/span><span style=\"font-weight: 400;\"> \"Investir dans des entreprises au service des femmes s'est av\u00e9r\u00e9 r\u00e9sistant aux bouleversements \u00e9conomiques, aux chocs politiques et aux catastrophes naturelles\", explique Alexa Blain, associ\u00e9e directrice chez Deetken Impact, qui g\u00e8re le fonds. \"Notre fonds Ilu est con\u00e7u pour s'appuyer sur ces r\u00e9sultats, avec pour mandat explicite d'offrir des rendements \u00e9lev\u00e9s et de faire progresser l'\u00e9galit\u00e9 des sexes en Am\u00e9rique latine.\"<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8438d2 elementor-widget elementor-widget-image\" data-id=\"c8438d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"623\" src=\"https:\/\/genuscap.com\/wp-content\/uploads\/2022\/03\/GENUS-Ilu-Womens-Empowerment-Fund-Feature-and-Inline-Image-1024x623.png\" class=\"attachment-large size-large wp-image-23612\" alt=\"\" srcset=\"https:\/\/genuscap.com\/wp-content\/uploads\/2022\/03\/GENUS-Ilu-Womens-Empowerment-Fund-Feature-and-Inline-Image-1024x623.png 1024w, https:\/\/genuscap.com\/wp-content\/uploads\/2022\/03\/GENUS-Ilu-Womens-Empowerment-Fund-Feature-and-Inline-Image-300x183.png 300w, https:\/\/genuscap.com\/wp-content\/uploads\/2022\/03\/GENUS-Ilu-Womens-Empowerment-Fund-Feature-and-Inline-Image-768x467.png 768w, https:\/\/genuscap.com\/wp-content\/uploads\/2022\/03\/GENUS-Ilu-Womens-Empowerment-Fund-Feature-and-Inline-Image-1536x934.png 1536w, https:\/\/genuscap.com\/wp-content\/uploads\/2022\/03\/GENUS-Ilu-Womens-Empowerment-Fund-Feature-and-Inline-Image-700x426.png 700w, https:\/\/genuscap.com\/wp-content\/uploads\/2022\/03\/GENUS-Ilu-Womens-Empowerment-Fund-Feature-and-Inline-Image.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a2636e elementor-widget elementor-widget-heading\" data-id=\"8a2636e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Comment l'Ilu fait bouger les choses en mati\u00e8re d'\u00e9galit\u00e9 entre les hommes et les femmes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1e8ecc elementor-widget elementor-widget-text-editor\" data-id=\"e1e8ecc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Ilu investit dans des entreprises latino-am\u00e9ricaines bien \u00e9tablies qui ont fait leurs preuves en mati\u00e8re d'activit\u00e9s durables. \"Nous recherchons des entreprises qui s'engagent en faveur de l'\u00e9galit\u00e9 des sexes\", explique Mme Blain. \"Cela comprend la gouvernance inclusive, les femmes dans le leadership, l'\u00e9quit\u00e9 sur le lieu de travail, le genre dans la cha\u00eene de valeur et la d\u00e9fense des int\u00e9r\u00eats de la communaut\u00e9, ainsi que les produits et services destin\u00e9s aux femmes. Ces entreprises n'ont pas besoin d'\u00eatre parfaites dans tous les domaines, mais nous recherchons une volont\u00e9 de faire progresser les pratiques en mati\u00e8re d'\u00e9galit\u00e9 des sexes.\"<\/span><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400;\">L'ann\u00e9e derni\u00e8re, l'Ilu a re\u00e7u un financement de l'USAID qui lui a permis de s'engager activement aupr\u00e8s des entreprises de son portefeuille et de travailler en \u00e9troite collaboration avec elles pour combler les \u00e9carts entre les sexes. \"Nous les accompagnons sur la voie de l'augmentation de l'impact\", explique Mme Blain. \"Par exemple, au Panama, l'un de nos clients, un pr\u00eateur, n'avait que 30% de clients dirig\u00e9s par des femmes et voulait augmenter ce chiffre. Nous l'avons donc aid\u00e9 \u00e0 r\u00e9aliser une \u00e9tude de march\u00e9 pour comprendre o\u00f9 il pouvait s'adresser \u00e0 davantage d'entreprises dirig\u00e9es par des femmes, puis \u00e0 cr\u00e9er des syst\u00e8mes d'information sexosp\u00e9cifiques pour affiner la mani\u00e8re dont il recueillait des donn\u00e9es sur ses clients. Il est important d'avoir <\/span><span style=\"font-weight: 400;\">\u00a0la connaissance du march\u00e9, non seulement en ce qui concerne les besoins et les pr\u00e9f\u00e9rences des femmes clientes, mais aussi les obstacles, les opportunit\u00e9s et les mod\u00e8les li\u00e9s au genre<\/span><span style=\"font-weight: 400;\">.\"<\/span><\/p><p>\u00a0<\/p><p><span style=\"font-weight: 400;\">Gr\u00e2ce \u00e0 ses programmes, l'Ilu a servi pr\u00e8s d'un demi-million de femmes, cr\u00e9ant des emplois, de l'\u00e9nergie durable, des services de sant\u00e9 et des formations en mati\u00e8re d'\u00e9ducation financi\u00e8re, et s'alignant sur cinq des objectifs du Mill\u00e9naire pour le d\u00e9veloppement (OMD) de l'ONU. <\/span><a href=\"https:\/\/sdgs.un.org\/goals\"><span style=\"font-weight: 400;\">Objectifs de d\u00e9veloppement durable<\/span><\/a><span style=\"font-weight: 400;\">.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7902b5 elementor-widget elementor-widget-heading\" data-id=\"d7902b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Investissement d'impact international et accessible<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c66df3 elementor-widget elementor-widget-text-editor\" data-id=\"1c66df3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Pourquoi se concentrer uniquement sur l'Am\u00e9rique latine ? C'est l\u00e0 que Jose Lamyin, cofondateur et associ\u00e9 g\u00e9rant de Deetken, avait les contacts n\u00e9cessaires pour cr\u00e9er le type d'impact sur le terrain qu'ils souhaitaient obtenir. \"Jose est p\u00e9ruvien\", explique M. Blain. \"Il avait d\u00e9j\u00e0 investi dans la r\u00e9gion et constitu\u00e9 un portefeuille d'investisseurs de Vancouver partageant les m\u00eames id\u00e9es. Nous avons fait \u00e9quipe pour d\u00e9velopper cette strat\u00e9gie et cr\u00e9er une entreprise de gestion d'actifs.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Aujourd'hui, Deetken emploie 25 personnes et dispose d'un bureau \u00e0 Vancouver, bien que 95% des membres de son \u00e9quipe soient bas\u00e9s dans les r\u00e9gions o\u00f9 elle investit : Costa Rica, Mexique, Guatemala, Honduras et P\u00e9rou.\u00a0<\/span><\/p><p><i><span style=\"font-weight: 400;\">\"Nous avons con\u00e7u le fonds de mani\u00e8re \u00e0 ce qu'il convienne aux investisseurs qui ne connaissent pas encore l'investissement d'impact, les march\u00e9s \u00e9mergents et les produits des march\u00e9s priv\u00e9s. \"\u00a0 <\/span><\/i><i><span style=\"font-weight: 400;\"><br \/><\/span><\/i><i><span style=\"font-weight: 400;\">- Alexa Blain, associ\u00e9e g\u00e9rante, Deetken Impact<\/span><\/i><\/p><p><span style=\"font-weight: 400;\">En cr\u00e9ant un point d'entr\u00e9e accessible pour les investisseurs \u00e0 impact, Ilu a \u00e9t\u00e9 adopt\u00e9 par les investisseurs novices dans le domaine de l'impact. \"Nous avons con\u00e7u le fonds de mani\u00e8re \u00e0 ce qu'il convienne aux investisseurs qui ne connaissent pas l'investissement d'impact, les march\u00e9s \u00e9mergents et les produits des march\u00e9s priv\u00e9s\", explique M. Blain.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Son offre la plus r\u00e9cente, un coupon d'obligation \u00e0 cinq ans de 5% avec une protection contre les premi\u00e8res pertes de 10%, signifie que le paiement aux investisseurs est garanti. \"Cela a aid\u00e9 les personnes r\u00e9ticentes \u00e0 investir en ajoutant une couche de protection\", explique M. Blain.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Alors que le fonds est sur le point d'achever ses 15 premiers projets d'engagement, les r\u00e9sultats positifs sont d\u00e9j\u00e0 \u00e9vidents. \"<\/span><span style=\"font-weight: 400;\">Bien que les projets se soient concentr\u00e9s sur un domaine d'activit\u00e9 dans chaque entreprise, il est tout \u00e0 fait clair qu'ils ont eu un effet boule de neige en lan\u00e7ant un mouvement d'int\u00e9gration de la dimension de genre \u00e0 l'\u00e9chelle de l'entreprise\", explique Mme Blain. \"Par exemple, une entreprise mexicaine a cr\u00e9\u00e9 deux nouveaux comit\u00e9s, un comit\u00e9 sur le genre et un comit\u00e9 sur les talents, afin de promouvoir la diversit\u00e9, l'\u00e9quit\u00e9 et l'inclusion dans l'ensemble des op\u00e9rations et le leadership des femmes en particulier. Elle a \u00e9galement \u00e9labor\u00e9 deux nouvelles politiques ax\u00e9es sur le harc\u00e8lement sexuel et la violence, ainsi que sur l'\u00e9galit\u00e9 des sexes et l'inclusion, afin de compl\u00e9ter ses intentions par une documentation et des lignes directrices sp\u00e9cifiques.\"<\/span><\/p><p><span style=\"font-weight: 400;\">Avec un tel bilan, M. Deetken est maintenant en mesure de choisir les entreprises dans lesquelles il investira \u00e0 l'avenir. \"<\/span><span style=\"font-weight: 400;\">Les opportunit\u00e9s viennent maintenant \u00e0 nous\", explique M. Blain. \"Avec $200 millions de dollars canadiens sous gestion, nous pouvons centraliser le pipeline de transactions et \u00e9valuer quels fonds pourraient \u00eatre les mieux adapt\u00e9s \u00e0 chaque opportunit\u00e9.\"<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dc684f elementor-widget elementor-widget-text-editor\" data-id=\"1dc684f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><i><span style=\"font-weight: 400;\">L'ILU est ferm\u00e9e aux nouveaux investisseurs, mais recommencera \u00e0 lever des capitaux en 2023. <\/span><\/i><a href=\"https:\/\/genuscap.com\/fr\/sur\/rencontrez-votre-equipe\/\"><b><i>Contactez un gestionnaire de portefeuille Genus pour savoir comment construire votre propre portefeuille d'impact.<\/i><\/b><\/a><i><span style=\"font-weight: 400;\">.<\/span><\/i><\/p><p><i><span style=\"font-weight: 400;\">Avis de non-responsabilit\u00e9 - Genus Capital<\/span><\/i><\/p><p><i><span style=\"font-weight: 400;\">Ce document a \u00e9t\u00e9 pr\u00e9par\u00e9 \u00e0 des fins d'information g\u00e9n\u00e9rale uniquement et ne doit pas \u00eatre consid\u00e9r\u00e9 comme un substitut \u00e0 des conseils professionnels sp\u00e9cifiques. En particulier, son contenu ne doit pas \u00eatre interpr\u00e9t\u00e9 comme un conseil ou une recommandation de quelque nature que ce soit en mati\u00e8re d'investissement, de droit, de comptabilit\u00e9, de fiscalit\u00e9 ou autre, ni comme le fondement d'une d\u00e9cision de faire ou de s'abstenir de faire quoi que ce soit. En tant que tel, ce document ne doit pas \u00eatre utilis\u00e9 pour prendre des d\u00e9cisions d'investissement ou d'autres d\u00e9cisions financi\u00e8res et aucune d\u00e9cision de ce type ne doit \u00eatre prise sur la base de son contenu sans demander des conseils sp\u00e9cifiques. Ce document est bas\u00e9 sur les informations dont dispose Genus Capital Management \u00e0 la date d'\u00e9mission et ne tient pas compte des d\u00e9veloppements ult\u00e9rieurs \u00e0 cette date. En outre, les performances pass\u00e9es ne sont pas indicatives des r\u00e9sultats futurs. En produisant ce document, Genus s'est appuy\u00e9 sur l'exactitude et l'exhaustivit\u00e9 de certaines donn\u00e9es et informations obtenues aupr\u00e8s de tiers. Les liens vers le site web de l'\u00e9metteur sont fournis pour des raisons de commodit\u00e9 et nous ne garantissons pas l'exactitude des informations et n'acceptons aucune responsabilit\u00e9 pour les informations publi\u00e9es sur leur site web.<\/span><\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Every investor wants their investments to perform financially. Impact investors also want them to perform socially \u2013 advancing solutions to important social issues. Deetken Impact has found a way to make both outcomes happen for Canadian investors looking to advance gender equality through private equity&#8230;<\/p>","protected":false},"author":6,"featured_media":23610,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[16,27],"tags":[110],"class_list":["post-23605","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-market-insights","tag-blog"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Impact Investors Empowering Latin Women - Genus Capital Management<\/title>\n<meta name=\"description\" content=\"Deetken Impact has found a way for Canadian investors to advance gender equality through private equity investments.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/genuscap.com\/fr\/how-canadian-impact-investors-are-empowering-latin-american-women\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How Canadian Impact Investors Are Empowering Latin American Women\" \/>\n<meta property=\"og:description\" content=\"Every investor wants their investments to perform financially. Impact investors also want them to perform socially \u2013 advancing solutions to important\" \/>\n<meta property=\"og:url\" content=\"https:\/\/genuscap.com\/fr\/how-canadian-impact-investors-are-empowering-latin-american-women\/\" \/>\n<meta property=\"og:site_name\" content=\"Genus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GenusCap\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-25T00:11:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-17T20:38:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/genuscap.com\/wp-content\/uploads\/2022\/03\/woman-with-fist-resize.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1013\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Genus Marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GenusCapMgt\" \/>\n<meta name=\"twitter:site\" content=\"@GenusCapMgt\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Genus Marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/genuscap.com\\\/how-canadian-impact-investors-are-empowering-latin-american-women\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/genuscap.com\\\/how-canadian-impact-investors-are-empowering-latin-american-women\\\/\"},\"author\":{\"name\":\"Genus Marketing\",\"@id\":\"https:\\\/\\\/genuscap.com\\\/#\\\/schema\\\/person\\\/dbc0cb75d28e9c72cc263dea334d6af7\"},\"headline\":\"How Canadian Impact Investors Are Empowering Latin American Women\",\"datePublished\":\"2022-03-25T00:11:31+00:00\",\"dateModified\":\"2026-03-17T20:38:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/genuscap.com\\\/how-canadian-impact-investors-are-empowering-latin-american-women\\\/\"},\"wordCount\":1008,\"publisher\":{\"@id\":\"https:\\\/\\\/genuscap.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/genuscap.com\\\/how-canadian-impact-investors-are-empowering-latin-american-women\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/genuscap.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/woman-with-fist-resize.jpg\",\"keywords\":[\"blog\"],\"articleSection\":[\"Blog\",\"Market Insights\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/genuscap.com\\\/how-canadian-impact-investors-are-empowering-latin-american-women\\\/\",\"url\":\"https:\\\/\\\/genuscap.com\\\/how-canadian-impact-investors-are-empowering-latin-american-women\\\/\",\"name\":\"Impact Investors Empowering Latin Women - Genus Capital Management\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/genuscap.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/genuscap.com\\\/how-canadian-impact-investors-are-empowering-latin-american-women\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/genuscap.com\\\/how-canadian-impact-investors-are-empowering-latin-american-women\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/genuscap.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/woman-with-fist-resize.jpg\",\"datePublished\":\"2022-03-25T00:11:31+00:00\",\"dateModified\":\"2026-03-17T20:38:23+00:00\",\"description\":\"Deetken Impact has found a way for Canadian investors to advance gender equality through private equity investments.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/genuscap.com\\\/how-canadian-impact-investors-are-empowering-latin-american-women\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/genuscap.com\\\/how-canadian-impact-investors-are-empowering-latin-american-women\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/genuscap.com\\\/how-canadian-impact-investors-are-empowering-latin-american-women\\\/#primaryimage\",\"url\":\"https:\\\/\\\/genuscap.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/woman-with-fist-resize.jpg\",\"contentUrl\":\"https:\\\/\\\/genuscap.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/woman-with-fist-resize.jpg\",\"width\":1920,\"height\":1013},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/genuscap.com\\\/how-canadian-impact-investors-are-empowering-latin-american-women\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/genuscap.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How Canadian Impact Investors Are Empowering Latin American Women\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/genuscap.com\\\/#website\",\"url\":\"https:\\\/\\\/genuscap.com\\\/\",\"name\":\"Genus\",\"description\":\"Impacting the future today, through innovative and sustainable investing\",\"publisher\":{\"@id\":\"https:\\\/\\\/genuscap.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/genuscap.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":[\"Organization\",\"Place\",\"FinancialService\"],\"@id\":\"https:\\\/\\\/genuscap.com\\\/#organization\",\"name\":\"Genus Capital Management\",\"url\":\"https:\\\/\\\/genuscap.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/genuscap.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/genuscap.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/genus_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/genuscap.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/genus_logo.jpg\",\"width\":358,\"height\":141,\"caption\":\"Genus Capital Management\"},\"image\":{\"@id\":\"https:\\\/\\\/genuscap.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GenusCap\",\"https:\\\/\\\/x.com\\\/GenusCapMgt\",\"https:\\\/\\\/www.instagram.com\\\/genuscapital\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/genus-capital-management\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCv-L-xC4xJD7V2Kyisle0uA\"],\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"860 - 980 Howe Street\",\"addressLocality\":\"Vancouver\",\"addressRegion\":\"BC\",\"postalCode\":\"V6Z 0C8\",\"addressCountry\":\"CA\"},\"geo\":{\"@type\":\"GeoCoordinates\",\"latitude\":\"49.28032195825037\",\"longitude\":\"-123.12350955767187\"},\"telephone\":\"+1-604-683-4554\",\"email\":\"info@genuscap.com\",\"priceRange\":\"$$\",\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\"],\"opens\":\"08:00\",\"closes\":\"16:30\"}],\"contactPoint\":[{\"@type\":\"ContactPoint\",\"contactType\":\"customer support\",\"telephone\":\"+1-800-668-7366\",\"email\":\"info@genuscap.com\",\"areaServed\":\"CA\",\"availableLanguage\":[\"English\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/genuscap.com\\\/#\\\/schema\\\/person\\\/dbc0cb75d28e9c72cc263dea334d6af7\",\"name\":\"Genus Marketing\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bafd6605c2f87f908791a25a22ab299c703044c398953bbcd07b0f03937b60a1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bafd6605c2f87f908791a25a22ab299c703044c398953bbcd07b0f03937b60a1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bafd6605c2f87f908791a25a22ab299c703044c398953bbcd07b0f03937b60a1?s=96&d=mm&r=g\",\"caption\":\"Genus Marketing\"},\"url\":\"https:\\\/\\\/genuscap.com\\\/fr\\\/author\\\/genus-marketing\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Impact Investors Empowering Latin Women - Genus Capital Management","description":"Deetken Impact has found a way for Canadian investors to advance gender equality through private equity investments.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/genuscap.com\/fr\/how-canadian-impact-investors-are-empowering-latin-american-women\/","og_locale":"fr_CA","og_type":"article","og_title":"How Canadian Impact Investors Are Empowering Latin American Women","og_description":"Every investor wants their investments to perform financially. Impact investors also want them to perform socially \u2013 advancing solutions to important","og_url":"https:\/\/genuscap.com\/fr\/how-canadian-impact-investors-are-empowering-latin-american-women\/","og_site_name":"Genus","article_publisher":"https:\/\/www.facebook.com\/GenusCap","article_published_time":"2022-03-25T00:11:31+00:00","article_modified_time":"2026-03-17T20:38:23+00:00","og_image":[{"width":1920,"height":1013,"url":"https:\/\/genuscap.com\/wp-content\/uploads\/2022\/03\/woman-with-fist-resize.jpg","type":"image\/jpeg"}],"author":"Genus Marketing","twitter_card":"summary_large_image","twitter_creator":"@GenusCapMgt","twitter_site":"@GenusCapMgt","twitter_misc":{"Written by":"Genus Marketing","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/genuscap.com\/how-canadian-impact-investors-are-empowering-latin-american-women\/#article","isPartOf":{"@id":"https:\/\/genuscap.com\/how-canadian-impact-investors-are-empowering-latin-american-women\/"},"author":{"name":"Genus Marketing","@id":"https:\/\/genuscap.com\/#\/schema\/person\/dbc0cb75d28e9c72cc263dea334d6af7"},"headline":"How Canadian Impact Investors Are Empowering Latin American Women","datePublished":"2022-03-25T00:11:31+00:00","dateModified":"2026-03-17T20:38:23+00:00","mainEntityOfPage":{"@id":"https:\/\/genuscap.com\/how-canadian-impact-investors-are-empowering-latin-american-women\/"},"wordCount":1008,"publisher":{"@id":"https:\/\/genuscap.com\/#organization"},"image":{"@id":"https:\/\/genuscap.com\/how-canadian-impact-investors-are-empowering-latin-american-women\/#primaryimage"},"thumbnailUrl":"https:\/\/genuscap.com\/wp-content\/uploads\/2022\/03\/woman-with-fist-resize.jpg","keywords":["blog"],"articleSection":["Blog","Market Insights"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/genuscap.com\/how-canadian-impact-investors-are-empowering-latin-american-women\/","url":"https:\/\/genuscap.com\/how-canadian-impact-investors-are-empowering-latin-american-women\/","name":"Impact Investors Empowering Latin Women - Genus Capital Management","isPartOf":{"@id":"https:\/\/genuscap.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/genuscap.com\/how-canadian-impact-investors-are-empowering-latin-american-women\/#primaryimage"},"image":{"@id":"https:\/\/genuscap.com\/how-canadian-impact-investors-are-empowering-latin-american-women\/#primaryimage"},"thumbnailUrl":"https:\/\/genuscap.com\/wp-content\/uploads\/2022\/03\/woman-with-fist-resize.jpg","datePublished":"2022-03-25T00:11:31+00:00","dateModified":"2026-03-17T20:38:23+00:00","description":"Deetken Impact has found a way for Canadian investors to advance gender equality through private equity investments.","breadcrumb":{"@id":"https:\/\/genuscap.com\/how-canadian-impact-investors-are-empowering-latin-american-women\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/genuscap.com\/how-canadian-impact-investors-are-empowering-latin-american-women\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/genuscap.com\/how-canadian-impact-investors-are-empowering-latin-american-women\/#primaryimage","url":"https:\/\/genuscap.com\/wp-content\/uploads\/2022\/03\/woman-with-fist-resize.jpg","contentUrl":"https:\/\/genuscap.com\/wp-content\/uploads\/2022\/03\/woman-with-fist-resize.jpg","width":1920,"height":1013},{"@type":"BreadcrumbList","@id":"https:\/\/genuscap.com\/how-canadian-impact-investors-are-empowering-latin-american-women\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/genuscap.com\/"},{"@type":"ListItem","position":2,"name":"How Canadian Impact Investors Are Empowering Latin American Women"}]},{"@type":"WebSite","@id":"https:\/\/genuscap.com\/#website","url":"https:\/\/genuscap.com\/","name":"Genre","description":"Avoir un impact sur l'avenir d\u00e8s aujourd'hui, gr\u00e2ce \u00e0 des investissements innovants et durables","publisher":{"@id":"https:\/\/genuscap.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/genuscap.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":["Organization","Place","FinancialService"],"@id":"https:\/\/genuscap.com\/#organization","name":"Genus Capital Management","url":"https:\/\/genuscap.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/genuscap.com\/#\/schema\/logo\/image\/","url":"https:\/\/genuscap.com\/wp-content\/uploads\/2021\/02\/genus_logo.jpg","contentUrl":"https:\/\/genuscap.com\/wp-content\/uploads\/2021\/02\/genus_logo.jpg","width":358,"height":141,"caption":"Genus Capital Management"},"image":{"@id":"https:\/\/genuscap.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GenusCap","https:\/\/x.com\/GenusCapMgt","https:\/\/www.instagram.com\/genuscapital\/","https:\/\/www.linkedin.com\/company\/genus-capital-management\/","https:\/\/www.youtube.com\/channel\/UCv-L-xC4xJD7V2Kyisle0uA"],"address":{"@type":"PostalAddress","streetAddress":"860 - 980 Howe Street","addressLocality":"Vancouver","addressRegion":"BC","postalCode":"V6Z 0C8","addressCountry":"CA"},"geo":{"@type":"GeoCoordinates","latitude":"49.28032195825037","longitude":"-123.12350955767187"},"telephone":"+1-604-683-4554","email":"info@genuscap.com","priceRange":"$$","openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday"],"opens":"08:00","closes":"16:30"}],"contactPoint":[{"@type":"ContactPoint","contactType":"customer support","telephone":"+1-800-668-7366","email":"info@genuscap.com","areaServed":"CA","availableLanguage":["English"]}]},{"@type":"Person","@id":"https:\/\/genuscap.com\/#\/schema\/person\/dbc0cb75d28e9c72cc263dea334d6af7","name":"Genus Marketing","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/bafd6605c2f87f908791a25a22ab299c703044c398953bbcd07b0f03937b60a1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bafd6605c2f87f908791a25a22ab299c703044c398953bbcd07b0f03937b60a1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bafd6605c2f87f908791a25a22ab299c703044c398953bbcd07b0f03937b60a1?s=96&d=mm&r=g","caption":"Genus Marketing"},"url":"https:\/\/genuscap.com\/fr\/author\/genus-marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/genuscap.com\/fr\/wp-json\/wp\/v2\/posts\/23605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/genuscap.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/genuscap.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/genuscap.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/genuscap.com\/fr\/wp-json\/wp\/v2\/comments?post=23605"}],"version-history":[{"count":0,"href":"https:\/\/genuscap.com\/fr\/wp-json\/wp\/v2\/posts\/23605\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/genuscap.com\/fr\/wp-json\/wp\/v2\/media\/23610"}],"wp:attachment":[{"href":"https:\/\/genuscap.com\/fr\/wp-json\/wp\/v2\/media?parent=23605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/genuscap.com\/fr\/wp-json\/wp\/v2\/categories?post=23605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/genuscap.com\/fr\/wp-json\/wp\/v2\/tags?post=23605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}